{"id":24158,"date":"2023-09-05T11:24:16","date_gmt":"2023-09-05T11:24:16","guid":{"rendered":"https:\/\/dibosch.com\/blog\/taller-de-higiene-de-manos-para-escuelas\/"},"modified":"2025-09-23T10:23:55","modified_gmt":"2025-09-23T10:23:55","slug":"taller-de-higiene-de-manos-para-escuelas","status":"publish","type":"post","link":"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/","title":{"rendered":"Taller de higiene de manos para escuelas"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos <\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57df9198fa1\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57df9198fa1\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Creamos_embajadores_de_higiene_de_manos_en_las_escuelas\" >Creamos embajadores de higiene de manos en las escuelas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Objetivo_del_taller\" >Objetivo del taller:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#%C2%BFA_quien_va_dirigido\" >\u00bfA qui\u00e9n va dirigido?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#%C2%BFDuracion_del_taller\" >\u00bfDuraci\u00f3n del taller?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Disponibilidad\" >Disponibilidad:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Localizacion\" >Localizaci\u00f3n:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Material\" >Material:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/dibosch.com\/es\/taller-de-higiene-de-manos-para-escuelas\/#Precio_Gratuito\" >Precio: Gratuito<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">La higiene de manos es un h\u00e1bito fundamental en la prevenci\u00f3n de enfermedades infecciosas junto con la higiene personal. La Organizaci\u00f3n Mundial de la Salud (OMS) destaca la importancia del lavado de manos como herramienta b\u00e1sica para prevenir las enfermedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Adem\u00e1s, seg\u00fan estimaciones de la Sociedad Espa\u00f1ola de Medicina Familiar y Comunitaria (semFYC), el 80% de las enfermedades infecciosas, como la gripe o el resfriado, se contagia a trav\u00e9s de sus manos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Reforzar las medidas de higiene y alcanzar buenos h\u00e1bitos desde peque\u00f1os es clave para limitar la propagaci\u00f3n de enfermedades y mantener espacios limpios y saludables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por este motivo, desde DIBOSCH ofrecemos un taller pr\u00e1ctico y divertido sobre higiene de manos gratuito para todas las escuelas interesadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Creamos_embajadores_de_higiene_de_manos_en_las_escuelas\"><\/span><br>Creamos embajadores de higiene de manos en las escuelas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"670\" src=\"https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1-1024x670.jpg\" alt=\"\" class=\"wp-image-24165\" srcset=\"https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1-1024x670.jpg 1024w, https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1-300x196.jpg 300w, https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1-768x502.jpg 768w, https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1-600x392.jpg 600w, https:\/\/dibosch.com\/wp-content\/uploads\/2023\/09\/taller-higiene-de-mans-escoles-1.jpg 1275w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Objetivo_del_taller\"><\/span>Objetivo del taller: <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer pedagog\u00eda y educar en la importancia de llevar a cabo un correcto proceso de lavado de manos para protegerse de las bacterias y microbios que a diario van a parar a nuestras manos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFA_quien_va_dirigido\"><\/span>\u00bfA qui\u00e9n va dirigido? <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Educaci\u00f3n primaria: Primer ciclo. Y educaci\u00f3n Infantil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFDuracion_del_taller\"><\/span>\u00bfDuraci\u00f3n del taller? <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Duraci\u00f3n aproximada: 30 &#8211; 45 minutos N\u00famero de alumnos: Grupo\/clase Se necesitar\u00e1 a una persona referente para coordinar todos los pasos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Disponibilidad\"><\/span>Disponibilidad:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Durante todo el a\u00f1o en horario de ma\u00f1anas o tardes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Localizacion\"><\/span>Localizaci\u00f3n:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Puede ser la misma aula o en alguna sala habilitada para la sesi\u00f3n. A ser posible con pantalla para poder proyectar una peque\u00f1a presentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Material\"><\/span>Material:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> No es necesario que la escuela aporte ning\u00fan material, DIBOSCH proporcionar\u00e1 a la escuela el material necesario para realizar las diferentes actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Precio_Gratuito\"><\/span>Precio: Gratuito<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Inscripciones: Reservar d\u00eda y hora con un m\u00ednimo de 15 d\u00edas de antelaci\u00f3n sobre la fecha prevista para la formaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para m\u00e1s informaci\u00f3n y reservas:<\/strong> Puede enviar un correo a info@dibosch.com o llamar al 972 477 052.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La higiene de manos es un h\u00e1bito fundamental en la prevenci\u00f3n de enfermedades infecciosas junto con la higiene personal. La Organizaci\u00f3n Mundial de la Salud (OMS) destaca la importancia del lavado de manos como herramienta b\u00e1sica para prevenir las enfermedades. Adem\u00e1s, seg\u00fan estimaciones de la Sociedad Espa\u00f1ola de Medicina Familiar y Comunitaria (semFYC), el 80% [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":24156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1241],"tags":[],"class_list":["post-24158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formaciones-es"],"_links":{"self":[{"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/posts\/24158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/comments?post=24158"}],"version-history":[{"count":1,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/posts\/24158\/revisions"}],"predecessor-version":[{"id":34982,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/posts\/24158\/revisions\/34982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/media\/24156"}],"wp:attachment":[{"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/media?parent=24158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/categories?post=24158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dibosch.com\/es\/wp-json\/wp\/v2\/tags?post=24158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}